{"id":9017,"date":"2019-11-20T09:00:41","date_gmt":"2019-11-20T08:00:41","guid":{"rendered":"https:\/\/vaporparalaindustria.com\/?p=9017"},"modified":"2020-06-11T14:39:59","modified_gmt":"2020-06-11T13:39:59","slug":"purgador-de-vapor-consideraciones-durante-la-eliminacion-condensado","status":"publish","type":"post","link":"https:\/\/vaporparalaindustria.com\/pt\/purgador-de-vapor-consideraciones-durante-la-eliminacion-condensado\/","title":{"rendered":"Armadilha de vapor: Considera\u00e7\u00f5es durante a remo\u00e7\u00e3o do condensado"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Para continuar com o <\/span><a href=\"https:\/\/vaporparalaindustria.com\/pt\/ejemplo-de-seleccion-de-purgadores-para-eliminacion-de-condensado\/\" target=\"_blank\" rel=\"noopener noreferrer\"><b>exemplo de sele\u00e7\u00e3o de um purgador para remo\u00e7\u00e3o de condensado<\/b><\/a><span style=\"font-weight: 400;\">Se a superf\u00edcie de aquecimento n\u00e3o for adequada para a condi\u00e7\u00e3o de design, chegou o momento de considerar o fornecedor \"Y\". Para que o fabricante possa dimensionar a superf\u00edcie de aquecimento que melhor se adapta \u00e0 condi\u00e7\u00e3o de projecto, \u00e9 necess\u00e1rio encontrar a superf\u00edcie de aquecimento m\u00ednima capaz de satisfazer a carga m\u00e1xima de funcionamento.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Primeiro, \u00e9 necess\u00e1rio determinar o LMTD nominal para o permutador de calor com uma press\u00e3o de espa\u00e7o de vapor de 4 bar r (T<\/span><b>S <\/b><span style=\"font-weight: 400;\">= 152 \u00b0C), a partir da equa\u00e7\u00e3o:<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9018 aligncenter\" src=\"https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor.png\" alt=\"\" width=\"1999\" height=\"1500\" srcset=\"https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-150x113.png 150w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-300x225.png 300w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-400x300.png 400w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-600x450.png 600w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-768x576.png 768w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-800x600.png 800w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-1024x768.png 1024w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-1200x900.png 1200w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-1536x1153.png 1536w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor.png 1999w\" sizes=\"auto, (max-width: 1999px) 100vw, 1999px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Usando a seguinte equa\u00e7\u00e3o, \u00e9 agora poss\u00edvel determinar a superf\u00edcie de aquecimento m\u00ednima para a pot\u00eancia nominal de 293 kW:<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9019 aligncenter\" src=\"https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-2.png\" alt=\"\" width=\"1999\" height=\"686\" srcset=\"https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-2-150x51.png 150w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-2-300x103.png 300w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-2-600x206.png 600w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-2-768x264.png 768w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-2-800x275.png 800w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-2-1024x351.png 1024w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-2-1536x527.png 1536w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-2.png 1999w\" sizes=\"auto, (max-width: 1999px) 100vw, 1999px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">A partir da sua gama standard, o fornecedor \"Y\" pode fornecer um <\/span><a href=\"https:\/\/vaporparalaindustria.com\/pt\/comparacion-entre-el-intercambiador-de-calor-de-placas-para-vapor-y-el-intercambiador-de-carcasa-y-tubos\/\" target=\"_blank\" rel=\"noopener noreferrer\"><b>permutador de calor de placas<\/b><\/a><span style=\"font-weight: 400;\"> que cumpre a especifica\u00e7\u00e3o com uma superf\u00edcie de aquecimento de 1.198 m2 . Este \u00e9 um valor sobredimensionado (aproximadamente 5 %) e portanto a press\u00e3o de vapor ser\u00e1 inferior a 4 bar r na condi\u00e7\u00e3o de opera\u00e7\u00e3o de carga m\u00e1xima.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Na pr\u00e1tica, \u00e9 prov\u00e1vel que <\/span><a href=\"https:\/\/vaporparalaindustria.com\/pt\/aplicaciones-de-los-intercambiadores-de-calor-de-placas-para-vapor-enteramente-soldados\/\" target=\"_blank\" rel=\"noopener noreferrer\"><b>permutadores de calor<\/b><\/a><span style=\"font-weight: 400;\"> s\u00e3o especificados com uma sobrecapacidade de pelo menos 10 %. Por este motivo, a press\u00e3o do vapor de opera\u00e7\u00e3o (n\u00e3o a press\u00e3o normal de trabalho especificada) deve ser sempre estabelecida antes de selecionar e dimensionar o dispositivo de ventila\u00e7\u00e3o de vapor.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Um fabricante respeit\u00e1vel deve estar preparado para fornecer estas informa\u00e7\u00f5es ou, pelo menos, a superf\u00edcie de aquecimento, o valor U e a sa\u00edda de calor. A partir destes dados, \u00e9 poss\u00edvel calcular o DMLT nominal, a partir do qual a press\u00e3o operacional pode ser determinada.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Calcular o DMLT para o permutador de calor com uma superf\u00edcie de aquecimento de 1.198 m2:<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9020 aligncenter\" src=\"https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-3.png\" alt=\"\" width=\"1999\" height=\"708\" srcset=\"https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-3-150x53.png 150w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-3-300x106.png 300w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-3-600x213.png 600w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-3-768x272.png 768w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-3-800x283.png 800w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-3-1024x363.png 1024w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-3-1536x544.png 1536w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-3.png 1999w\" sizes=\"auto, (max-width: 1999px) 100vw, 1999px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">A temperatura do vapor de funcionamento a plena carga pode agora ser calculada utilizando a seguinte equa\u00e7\u00e3o:<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9021 aligncenter\" src=\"https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-4.png\" alt=\"\" width=\"1869\" height=\"1999\" srcset=\"https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-4-140x150.png 140w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-4-280x300.png 280w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-4-561x600.png 561w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-4-600x642.png 600w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-4-768x821.png 768w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-4-957x1024.png 957w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-4-1436x1536.png 1436w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-4.png 1869w\" sizes=\"auto, (max-width: 1869px) 100vw, 1869px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Esta temperatura de satura\u00e7\u00e3o \u00e9 equivalente a uma press\u00e3o de vapor de 3,4 bar r na condi\u00e7\u00e3o de projecto. Como esta press\u00e3o \u00e9 maior que a contrapress\u00e3o constante de 0,5 bar r, o sistema n\u00e3o exibir\u00e1 interrup\u00e7\u00e3o do fluxo em carga m\u00e1xima.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<h3><b>Qual \u00e9 o caudal de vapor (ms) a plena carga?<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">O caudal m\u00e1ssico de vapor depender\u00e1 da press\u00e3o do espa\u00e7o de vapor, que \u00e9 de 3,4 bar r a plena carga, com uma entalpia de evapora\u00e7\u00e3o de 2.122 kJ<\/span><span style=\"font-weight: 400;\">\/<\/span><span style=\"font-weight: 400;\">kg, a partir da seguinte equa\u00e7\u00e3o:<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9022 aligncenter\" src=\"https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-5.png\" alt=\"\" width=\"1999\" height=\"515\" srcset=\"https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-5-150x39.png 150w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-5-300x77.png 300w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-5-600x155.png 600w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-5-768x198.png 768w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-5-800x206.png 800w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-5-1024x264.png 1024w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-5-1536x396.png 1536w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-5.png 1999w\" sizes=\"auto, (max-width: 1999px) 100vw, 1999px\" \/><\/p>\n<h3><b>O que \u00e9 o CDT?\u00a0<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Agora \u00e9 necess\u00e1rio descobrir a carga de calor na qual o sistema ir\u00e1 mostrar interrup\u00e7\u00e3o do fluxo. Para isso, \u00e9 necess\u00e1rio calcular o TDC para este permutador de calor a partir das condi\u00e7\u00f5es de projecto, a partir da seguinte equa\u00e7\u00e3o:<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9023 aligncenter\" src=\"https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-6.png\" alt=\"\" width=\"1999\" height=\"910\" srcset=\"https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-6-150x68.png 150w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-6-300x137.png 300w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-6-600x273.png 600w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-6-768x350.png 768w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-6-800x364.png 800w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-6-1024x466.png 1024w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-6-1536x699.png 1536w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-6.png 1999w\" sizes=\"auto, (max-width: 1999px) 100vw, 1999px\" \/><\/p>\n<h3><b>A condi\u00e7\u00e3o de interrup\u00e7\u00e3o do fluxo\u00a0<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Com <\/span><a href=\"https:\/\/vaporparalaindustria.com\/pt\/que-significa-la-interrupcion-del-flujo-en-intercambiadores-para-vapor\/\"><b>interrup\u00e7\u00e3o do fluxo<\/b><\/a><span style=\"font-weight: 400;\">a press\u00e3o no espa\u00e7o de vapor ser\u00e1 igual \u00e0 contrapress\u00e3o de 0,5 bar r. A temperatura de satura\u00e7\u00e3o do vapor a 0,5 bar r \u00e9 de 111,6 \u00b0C. A partir da seguinte equa\u00e7\u00e3o \u00e9 poss\u00edvel calcular a temperatura de entrada:<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9024 aligncenter\" src=\"https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-7.png\" alt=\"\" width=\"1999\" height=\"813\" srcset=\"https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-7-150x61.png 150w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-7-300x122.png 300w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-7-600x244.png 600w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-7-768x312.png 768w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-7-800x325.png 800w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-7-1024x416.png 1024w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-7-1536x625.png 1536w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-7.png 1999w\" sizes=\"auto, (max-width: 1999px) 100vw, 1999px\" \/><\/p>\n<h3><b>Qual \u00e9 a carga de calor no momento da interrup\u00e7\u00e3o do fluxo?\u00a0<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">A partir da seguinte equa\u00e7\u00e3o de taxa de transfer\u00eancia de calor:<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9025 aligncenter\" src=\"https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-8.png\" alt=\"\" width=\"1999\" height=\"1010\" srcset=\"https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-8-150x76.png 150w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-8-300x152.png 300w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-8-600x303.png 600w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-8-768x388.png 768w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-8-800x404.png 800w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-8-1024x517.png 1024w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-8-1536x776.png 1536w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-8.png 1999w\" sizes=\"auto, (max-width: 1999px) 100vw, 1999px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Como a carga m\u00ednima \u00e9 maior que a carga de interrup\u00e7\u00e3o do fluxo, o sistema n\u00e3o sofrer\u00e1 interrup\u00e7\u00e3o do fluxo. Portanto, \u00e9 poss\u00edvel instalar um purgador de b\u00f3ia fechado, pois sempre haver\u00e1 uma press\u00e3o diferencial positiva atrav\u00e9s do purgador.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">No entanto, o purgador de b\u00f3ia fechada deve ser dimensionado para atender tanto a carga m\u00e1xima quanto a carga m\u00ednima, portanto \u00e9 necess\u00e1rio calcular as vaz\u00f5es de vapor correspondentes e as press\u00f5es do espa\u00e7o de vapor sob ambas as condi\u00e7\u00f5es.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Em primeiro lugar, \u00e9 necess\u00e1rio calcular a temperatura de entrada do secund\u00e1rio com carga m\u00ednima. Pode ser previsto atrav\u00e9s da seguinte equa\u00e7\u00e3o: <\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9026 aligncenter\" src=\"https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-9.png\" alt=\"\" width=\"1999\" height=\"1260\" srcset=\"https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-9-150x95.png 150w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-9-300x189.png 300w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-9-600x378.png 600w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-9-768x484.png 768w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-9-800x504.png 800w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-9-1024x645.png 1024w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-9-1536x968.png 1536w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-9.png 1999w\" sizes=\"auto, (max-width: 1999px) 100vw, 1999px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">A condi\u00e7\u00e3o de carga m\u00ednima, a partir da seguinte equa\u00e7\u00e3o:<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9027 aligncenter\" src=\"https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-10.png\" alt=\"\" width=\"1999\" height=\"1065\" srcset=\"https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-10-150x80.png 150w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-10-300x160.png 300w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-10-600x320.png 600w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-10-768x409.png 768w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-10-800x426.png 800w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-10-1024x546.png 1024w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-10-1536x818.png 1536w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-10.png 1999w\" sizes=\"auto, (max-width: 1999px) 100vw, 1999px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Esta \u00e9 a temperatura do vapor \u00e0 carga m\u00ednima de 176 kW e equivale a uma press\u00e3o de vapor de 1,0 bar r. A press\u00e3o do condensado \u00e9 de 0,5 bar r. Portanto, a press\u00e3o diferencial atrav\u00e9s do purgador de vapor do flutuador fechado com carga m\u00ednima \u00e9 de 1,0 bar r - 0,5 bar r = 0,5 bar.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<h3><b>Qual \u00e9 o caudal de vapor ( s(min)) com a carga m\u00ednima de calor de 176 kW?\u00a0<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">O caudal m\u00ednimo de vapor depende da press\u00e3o do espa\u00e7o de vapor, que \u00e9 de 1,0 bar r com uma entalpia de evapora\u00e7\u00e3o de 2201,1 kJ\/kg, a partir da seguinte equa\u00e7\u00e3o<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9028 aligncenter\" src=\"https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-11.png\" alt=\"\" width=\"1999\" height=\"485\" srcset=\"https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-11-150x36.png 150w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-11-300x73.png 300w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-11-600x146.png 600w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-11-768x186.png 768w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-11-800x194.png 800w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-11-1024x248.png 1024w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-11-1536x373.png 1536w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-11.png 1999w\" sizes=\"auto, (max-width: 1999px) 100vw, 1999px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Como foi estabelecido que este sistema n\u00e3o sofrer\u00e1 interrup\u00e7\u00e3o de fluxo, um purgador de vapor de flutua\u00e7\u00e3o fechado seria adequado. Agora \u00e9 necess\u00e1rio dimensionar um purgador de vapor de flutua\u00e7\u00e3o fechado para operar at\u00e9 a press\u00e3o diferencial m\u00e1xima do sistema de 3,5 bar:<\/span><\/p>\n<ol>\n<li><span style=\"font-weight: 400;\">A carga m\u00e1xima de 498 kg\/h com uma press\u00e3o diferencial de 3,4 bar r - 0,5 bar r = 2,9 bar r.\u00a0<\/span><\/li>\n<li><span style=\"font-weight: 400;\">A carga m\u00ednima de 288 kg\/h com uma press\u00e3o diferencial de 1,0 bar r - 0,5 bar r = 0,5 bar r.\u00a0<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">Pode ser visto na tabela de dimensionamento do purgador no gr\u00e1fico abaixo que um DN25 (1\") FT14-4.5 ir\u00e1 atender a ambas as condi\u00e7\u00f5es e pode ser selecionado. No entanto, se a carga m\u00ednima de calor for inferior \u00e0 carga de interrup\u00e7\u00e3o do fluxo, seria necess\u00e1rio seleccionar um colector de bomba.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9029 aligncenter\" src=\"https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-12.png\" alt=\"\" width=\"1540\" height=\"1999\" srcset=\"https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-12-116x150.png 116w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-12-231x300.png 231w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-12-462x600.png 462w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-12-600x779.png 600w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-12-768x997.png 768w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-12-789x1024.png 789w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-12-1183x1536.png 1183w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor-12.png 1540w\" sizes=\"auto, (max-width: 1540px) 100vw, 1540px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Os m\u00e9todos para a sele\u00e7\u00e3o de dispositivos de purga s\u00e3o detalhados a partir do artigo <\/span><a href=\"https:\/\/vaporparalaindustria.com\/pt\/metodo-grafico-de-interrupcion-de-flujo-en-sistemas-de-vapor\/\" target=\"_blank\" rel=\"noopener noreferrer\"><b>m\u00e9todo gr\u00e1fico de interrup\u00e7\u00e3o de fluxo em sistemas de vapor<\/b><\/a><span style=\"font-weight: 400;\">. Convidamo-lo a conhecer o <\/span><a href=\"https:\/\/vaporparalaindustria.com\/pt\/tipos-de-purgadores-de-vapor-eliminar-condensado\/\" target=\"_blank\" rel=\"noopener noreferrer\"><b>tipos de purgadores para remo\u00e7\u00e3o de condensado<\/b><\/a><span style=\"font-weight: 400;\">bem como para subscrever o\u00a0<\/span><a href=\"https:\/\/vaporparalaindustria.com\/pt\/newsletter\/?utm_source=newsletter&amp;utm_medium=cta_vapor&amp;utm_campaign=vapor_cta_newsletter\" target=\"_blank\" rel=\"noopener noreferrer\"><b>Boletim Informativo Steam for Industry<\/b><\/a><span style=\"font-weight: 400;\">Um recurso que o ajudar\u00e1 a receber mais conte\u00fado sobre as novas tend\u00eancias em vapor industrial.<\/span><\/p>\n<p><a href=\"https:\/\/vaporparalaindustria.com\/pt\/auditoria-gratuita-de-calidad-del-vapor-para-procesos-alimentarios\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-7581 size-full\" src=\"https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2018\/07\/evaluacion-gratuita-procesos-alimentarios.003.jpeg\" alt=\"EVALUACION SISTEMA DE VAPOR Y CONDENSADO.001\" width=\"802\" height=\"181\" srcset=\"https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2018\/07\/evaluacion-gratuita-procesos-alimentarios.003-150x34.jpeg 150w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2018\/07\/evaluacion-gratuita-procesos-alimentarios.003-300x68.jpeg 300w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2018\/07\/evaluacion-gratuita-procesos-alimentarios.003-600x135.jpeg 600w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2018\/07\/evaluacion-gratuita-procesos-alimentarios.003-768x173.jpeg 768w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2018\/07\/evaluacion-gratuita-procesos-alimentarios.003-800x181.jpeg 800w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2018\/07\/evaluacion-gratuita-procesos-alimentarios.003.jpeg 802w\" sizes=\"auto, (max-width: 802px) 100vw, 802px\" \/><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Para continuar com o exemplo de sele\u00e7\u00e3o de um purgador para remo\u00e7\u00e3o de condensado, \u00e9 hora de considerar o fornecedor \"Y\". Para que o fabricante possa dimensionar a superf\u00edcie de aquecimento que melhor se adapte \u00e0 condi\u00e7\u00e3o de design, \u00e9 necess\u00e1rio encontrar a superf\u00edcie de aquecimento m\u00ednima capaz de satisfazer a condi\u00e7\u00e3o de design e a superf\u00edcie de aquecimento m\u00ednima ...<\/p>","protected":false},"author":1,"featured_media":9030,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[78],"tags":[],"class_list":["type-post","category-intercambiadores-de-calor-con-vapor","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Purgador de vapor: Consideraciones durante la eliminaci\u00f3n condensado<\/title>\n<meta name=\"description\" content=\"Este es el primero de una serie de tres art\u00edculos en los cuales mostraremos un ejemplo de selecci\u00f3n de purgadores para eliminaci\u00f3n de condensado.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vaporparalaindustria.com\/pt\/purgador-de-vapor-consideraciones-durante-la-eliminacion-condensado\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Purgador de vapor: Consideraciones durante la eliminaci\u00f3n condensado\" \/>\n<meta property=\"og:description\" content=\"Este es el primero de una serie de tres art\u00edculos en los cuales mostraremos un ejemplo de selecci\u00f3n de purgadores para eliminaci\u00f3n de condensado.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vaporparalaindustria.com\/pt\/purgador-de-vapor-consideraciones-durante-la-eliminacion-condensado\/\" \/>\n<meta property=\"og:site_name\" content=\"Vapor para la Industria\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-20T08:00:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-11T13:39:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Soporte\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Soporte\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vaporparalaindustria.com\\\/purgador-de-vapor-consideraciones-durante-la-eliminacion-condensado\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vaporparalaindustria.com\\\/purgador-de-vapor-consideraciones-durante-la-eliminacion-condensado\\\/\"},\"author\":{\"name\":\"Soporte\",\"@id\":\"https:\\\/\\\/vaporparalaindustria.com\\\/#\\\/schema\\\/person\\\/d64ca106960ba7ec5a51834fbecba681\"},\"headline\":\"Purgador de vapor: Consideraciones durante la eliminaci\u00f3n condensado\",\"datePublished\":\"2019-11-20T08:00:41+00:00\",\"dateModified\":\"2020-06-11T13:39:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vaporparalaindustria.com\\\/purgador-de-vapor-consideraciones-durante-la-eliminacion-condensado\\\/\"},\"wordCount\":996,\"publisher\":{\"@id\":\"https:\\\/\\\/vaporparalaindustria.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vaporparalaindustria.com\\\/purgador-de-vapor-consideraciones-durante-la-eliminacion-condensado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vaporparalaindustria.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Purgador-de-vapor.jpg\",\"articleSection\":[\"Intercambiadores de Calor con Vapor\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vaporparalaindustria.com\\\/purgador-de-vapor-consideraciones-durante-la-eliminacion-condensado\\\/\",\"url\":\"https:\\\/\\\/vaporparalaindustria.com\\\/purgador-de-vapor-consideraciones-durante-la-eliminacion-condensado\\\/\",\"name\":\"Purgador de vapor: Consideraciones durante la eliminaci\u00f3n condensado\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vaporparalaindustria.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vaporparalaindustria.com\\\/purgador-de-vapor-consideraciones-durante-la-eliminacion-condensado\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vaporparalaindustria.com\\\/purgador-de-vapor-consideraciones-durante-la-eliminacion-condensado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vaporparalaindustria.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Purgador-de-vapor.jpg\",\"datePublished\":\"2019-11-20T08:00:41+00:00\",\"dateModified\":\"2020-06-11T13:39:59+00:00\",\"description\":\"Este es el primero de una serie de tres art\u00edculos en los cuales mostraremos un ejemplo de selecci\u00f3n de purgadores para eliminaci\u00f3n de condensado.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vaporparalaindustria.com\\\/purgador-de-vapor-consideraciones-durante-la-eliminacion-condensado\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vaporparalaindustria.com\\\/purgador-de-vapor-consideraciones-durante-la-eliminacion-condensado\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/vaporparalaindustria.com\\\/purgador-de-vapor-consideraciones-durante-la-eliminacion-condensado\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vaporparalaindustria.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Purgador-de-vapor.jpg\",\"contentUrl\":\"https:\\\/\\\/vaporparalaindustria.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Purgador-de-vapor.jpg\",\"width\":1200,\"height\":600,\"caption\":\"Purgador de vapor\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vaporparalaindustria.com\\\/purgador-de-vapor-consideraciones-durante-la-eliminacion-condensado\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vaporparalaindustria.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Purgador de vapor: Consideraciones durante la eliminaci\u00f3n condensado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vaporparalaindustria.com\\\/#website\",\"url\":\"https:\\\/\\\/vaporparalaindustria.com\\\/\",\"name\":\"Vapor para la Industria\",\"description\":\"Gesti\u00f3n Eficiente de los Sistemas de Vapor\",\"publisher\":{\"@id\":\"https:\\\/\\\/vaporparalaindustria.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vaporparalaindustria.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vaporparalaindustria.com\\\/#organization\",\"name\":\"Vapor para la Industria\",\"url\":\"https:\\\/\\\/vaporparalaindustria.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/vaporparalaindustria.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/vaporparalaindustria.com\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/LogoBlogBLANCO-FINAL_VAPOR-PARA-LA-INDUSTRIA-e1499957507814.png\",\"contentUrl\":\"https:\\\/\\\/vaporparalaindustria.com\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/LogoBlogBLANCO-FINAL_VAPOR-PARA-LA-INDUSTRIA-e1499957507814.png\",\"width\":300,\"height\":117,\"caption\":\"Vapor para la Industria\"},\"image\":{\"@id\":\"https:\\\/\\\/vaporparalaindustria.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vaporparalaindustria.com\\\/#\\\/schema\\\/person\\\/d64ca106960ba7ec5a51834fbecba681\",\"name\":\"Soporte\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/daafa31e3c3038855edc007ca2e41a7f1af1259b6b79b93359d6de82934c5943?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/daafa31e3c3038855edc007ca2e41a7f1af1259b6b79b93359d6de82934c5943?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/daafa31e3c3038855edc007ca2e41a7f1af1259b6b79b93359d6de82934c5943?s=96&d=mm&r=g\",\"caption\":\"Soporte\"},\"url\":\"https:\\\/\\\/vaporparalaindustria.com\\\/pt\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Armadilha de vapor: Considera\u00e7\u00f5es durante a remo\u00e7\u00e3o do condensado","description":"Este \u00e9 o primeiro de uma s\u00e9rie de tr\u00eas artigos em que mostraremos um exemplo de sele\u00e7\u00e3o de drenos de condensados.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vaporparalaindustria.com\/pt\/purgador-de-vapor-consideraciones-durante-la-eliminacion-condensado\/","og_locale":"pt_PT","og_type":"article","og_title":"Purgador de vapor: Consideraciones durante la eliminaci\u00f3n condensado","og_description":"Este es el primero de una serie de tres art\u00edculos en los cuales mostraremos un ejemplo de selecci\u00f3n de purgadores para eliminaci\u00f3n de condensado.","og_url":"https:\/\/vaporparalaindustria.com\/pt\/purgador-de-vapor-consideraciones-durante-la-eliminacion-condensado\/","og_site_name":"Vapor para la Industria","article_published_time":"2019-11-20T08:00:41+00:00","article_modified_time":"2020-06-11T13:39:59+00:00","og_image":[{"width":1200,"height":600,"url":"https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor.jpg","type":"image\/jpeg"}],"author":"Soporte","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Soporte","Tempo estimado de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vaporparalaindustria.com\/purgador-de-vapor-consideraciones-durante-la-eliminacion-condensado\/#article","isPartOf":{"@id":"https:\/\/vaporparalaindustria.com\/purgador-de-vapor-consideraciones-durante-la-eliminacion-condensado\/"},"author":{"name":"Soporte","@id":"https:\/\/vaporparalaindustria.com\/#\/schema\/person\/d64ca106960ba7ec5a51834fbecba681"},"headline":"Purgador de vapor: Consideraciones durante la eliminaci\u00f3n condensado","datePublished":"2019-11-20T08:00:41+00:00","dateModified":"2020-06-11T13:39:59+00:00","mainEntityOfPage":{"@id":"https:\/\/vaporparalaindustria.com\/purgador-de-vapor-consideraciones-durante-la-eliminacion-condensado\/"},"wordCount":996,"publisher":{"@id":"https:\/\/vaporparalaindustria.com\/#organization"},"image":{"@id":"https:\/\/vaporparalaindustria.com\/purgador-de-vapor-consideraciones-durante-la-eliminacion-condensado\/#primaryimage"},"thumbnailUrl":"https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor.jpg","articleSection":["Intercambiadores de Calor con Vapor"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/vaporparalaindustria.com\/purgador-de-vapor-consideraciones-durante-la-eliminacion-condensado\/","url":"https:\/\/vaporparalaindustria.com\/purgador-de-vapor-consideraciones-durante-la-eliminacion-condensado\/","name":"Armadilha de vapor: Considera\u00e7\u00f5es durante a remo\u00e7\u00e3o do condensado","isPartOf":{"@id":"https:\/\/vaporparalaindustria.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vaporparalaindustria.com\/purgador-de-vapor-consideraciones-durante-la-eliminacion-condensado\/#primaryimage"},"image":{"@id":"https:\/\/vaporparalaindustria.com\/purgador-de-vapor-consideraciones-durante-la-eliminacion-condensado\/#primaryimage"},"thumbnailUrl":"https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor.jpg","datePublished":"2019-11-20T08:00:41+00:00","dateModified":"2020-06-11T13:39:59+00:00","description":"Este \u00e9 o primeiro de uma s\u00e9rie de tr\u00eas artigos em que mostraremos um exemplo de sele\u00e7\u00e3o de drenos de condensados.","breadcrumb":{"@id":"https:\/\/vaporparalaindustria.com\/purgador-de-vapor-consideraciones-durante-la-eliminacion-condensado\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vaporparalaindustria.com\/purgador-de-vapor-consideraciones-durante-la-eliminacion-condensado\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/vaporparalaindustria.com\/purgador-de-vapor-consideraciones-durante-la-eliminacion-condensado\/#primaryimage","url":"https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor.jpg","contentUrl":"https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor.jpg","width":1200,"height":600,"caption":"Purgador de vapor"},{"@type":"BreadcrumbList","@id":"https:\/\/vaporparalaindustria.com\/purgador-de-vapor-consideraciones-durante-la-eliminacion-condensado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vaporparalaindustria.com\/"},{"@type":"ListItem","position":2,"name":"Purgador de vapor: Consideraciones durante la eliminaci\u00f3n condensado"}]},{"@type":"WebSite","@id":"https:\/\/vaporparalaindustria.com\/#website","url":"https:\/\/vaporparalaindustria.com\/","name":"Vapor para a Ind\u00fastria","description":"Gest\u00e3o Eficiente de Sistemas a Vapor","publisher":{"@id":"https:\/\/vaporparalaindustria.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vaporparalaindustria.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/vaporparalaindustria.com\/#organization","name":"Vapor para a Ind\u00fastria","url":"https:\/\/vaporparalaindustria.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/vaporparalaindustria.com\/#\/schema\/logo\/image\/","url":"https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2017\/10\/LogoBlogBLANCO-FINAL_VAPOR-PARA-LA-INDUSTRIA-e1499957507814.png","contentUrl":"https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2017\/10\/LogoBlogBLANCO-FINAL_VAPOR-PARA-LA-INDUSTRIA-e1499957507814.png","width":300,"height":117,"caption":"Vapor para la Industria"},"image":{"@id":"https:\/\/vaporparalaindustria.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/vaporparalaindustria.com\/#\/schema\/person\/d64ca106960ba7ec5a51834fbecba681","name":"Suporte","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/daafa31e3c3038855edc007ca2e41a7f1af1259b6b79b93359d6de82934c5943?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/daafa31e3c3038855edc007ca2e41a7f1af1259b6b79b93359d6de82934c5943?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/daafa31e3c3038855edc007ca2e41a7f1af1259b6b79b93359d6de82934c5943?s=96&d=mm&r=g","caption":"Soporte"},"url":"https:\/\/vaporparalaindustria.com\/pt\/author\/admin\/"}]}},"acf":[],"fimg_url":"https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/11\/Purgador-de-vapor.jpg","_links":{"self":[{"href":"https:\/\/vaporparalaindustria.com\/pt\/wp-json\/wp\/v2\/posts\/9017","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vaporparalaindustria.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vaporparalaindustria.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vaporparalaindustria.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vaporparalaindustria.com\/pt\/wp-json\/wp\/v2\/comments?post=9017"}],"version-history":[{"count":0,"href":"https:\/\/vaporparalaindustria.com\/pt\/wp-json\/wp\/v2\/posts\/9017\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vaporparalaindustria.com\/pt\/wp-json\/wp\/v2\/media\/9030"}],"wp:attachment":[{"href":"https:\/\/vaporparalaindustria.com\/pt\/wp-json\/wp\/v2\/media?parent=9017"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vaporparalaindustria.com\/pt\/wp-json\/wp\/v2\/categories?post=9017"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vaporparalaindustria.com\/pt\/wp-json\/wp\/v2\/tags?post=9017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}