{"id":8694,"date":"2019-07-24T09:00:45","date_gmt":"2019-07-24T08:00:45","guid":{"rendered":"https:\/\/vaporparalaindustria.com\/?p=8694"},"modified":"2020-06-11T14:39:59","modified_gmt":"2020-06-11T13:39:59","slug":"condicion-de-interrupcion-en-intercambiadores-de-vapor-de-placas-parte-2","status":"publish","type":"post","link":"https:\/\/vaporparalaindustria.com\/pt\/condicion-de-interrupcion-en-intercambiadores-de-vapor-de-placas-parte-2\/","title":{"rendered":"Condi\u00e7\u00e3o de corte em permutadores de vapor tipo placa (Parte 2)"},"content":{"rendered":"<p>Se a contrapress\u00e3o imposta a uma armadilha for maior do que a press\u00e3o dispon\u00edvel na sua entrada, diz-se que os permutadores de vapor de placas est\u00e3o em \"condi\u00e7\u00e3o de corte\". O condensado n\u00e3o pode passar atrav\u00e9s da armadilha e flui de volta, resultando na perda do controle efetivo sobre o trocador.<\/p>\n<p>O ponto em que esta condi\u00e7\u00e3o ocorrer\u00e1 em uma determinada aplica\u00e7\u00e3o pode ser previsto, seja por c\u00e1lculo ou tra\u00e7ando as condi\u00e7\u00f5es de opera\u00e7\u00e3o conhecidas em um gr\u00e1fico e fazendo leituras dos pontos de parada. Ambos os m\u00e9todos podem ser ilustrados em exemplos.<\/p>\n<p>&nbsp;<\/p>\n<h3><b>C\u00e1lculo do estado de avaria em permutadores de vapor tipo placa<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Requer um <\/span><a href=\"https:\/\/vaporparalaindustria.com\/pt\/comparacion-entre-el-intercambiador-de-calor-de-placas-para-vapor-y-el-intercambiador-de-carcasa-y-tubos\/\" target=\"_blank\" rel=\"noopener noreferrer\"><b>permutador de calor de placas<\/b><\/a><span style=\"font-weight: 400;\"> para aquecer 4 kg\/s de \u00e1gua de 30oC a 90oC. O vapor est\u00e1 dispon\u00edvel a 4 bar r e inicialmente assume-se que haver\u00e1 uma queda de press\u00e3o de 25% atrav\u00e9s da v\u00e1lvula de controlo de temperatura, fornecendo 3 bar r ao permutador de calor. O condensado \u00e9 descarregado para um sistema de retorno a 0 bar r. Para dar o desempenho necess\u00e1rio e proporcionar uma queda de press\u00e3o razo\u00e1vel de aproximadamente 35 kPa ao secund\u00e1rio, foi seleccionado um permutador de calor de placas de vapor com uma superf\u00edcie de transfer\u00eancia de calor de 2,6 m2 e um coeficiente de transfer\u00eancia de calor (k) de 7.450 W\/ m2 oC. Primeiro, a carga t\u00e9rmica total de projeto \u00e9 calculada, usando a seguinte f\u00f3rmula \"A\".<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A partir das informa\u00e7\u00f5es agora dispon\u00edveis, podemos calcular a temperatura m\u00e9dia aritm\u00e9tica real, para dar o desempenho de carga completa necess\u00e1ria, como mostrado na f\u00f3rmula \"B\".<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-8695\" src=\"\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/07\/Intercambiadores-de-vapor-de-placas.jpg\" alt=\"Permutadores de vapor placas\" width=\"1200\" height=\"600\" srcset=\"https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/07\/Intercambiadores-de-vapor-de-placas-150x75.jpg 150w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/07\/Intercambiadores-de-vapor-de-placas-300x150.jpg 300w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/07\/Intercambiadores-de-vapor-de-placas-600x300.jpg 600w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/07\/Intercambiadores-de-vapor-de-placas-768x384.jpg 768w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/07\/Intercambiadores-de-vapor-de-placas-800x400.jpg 800w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/07\/Intercambiadores-de-vapor-de-placas-1024x512.jpg 1024w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/07\/Intercambiadores-de-vapor-de-placas.jpg 1200w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Como a temperatura m\u00e9dia secund\u00e1ria \u00e9 fixa, a temperatura m\u00e9dia prim\u00e1ria de carga total TH(in), necess\u00e1ria para fornecer esta diferen\u00e7a de temperatura m\u00e9dia aritm\u00e9tica global, pode ser calculada atrav\u00e9s da f\u00f3rmula \"C\".<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Das tabelas de vapor pode-se ver que esta temperatura de 112oC \u00e9 equivalente a uma press\u00e3o de vapor saturada de aproximadamente 0,5 bar r. Este exemplo mostra que, independentemente da press\u00e3o de vapor dispon\u00edvel a montante do <\/span><a href=\"https:\/\/vaporparalaindustria.com\/pt\/20-factores-a-tener-en-cuenta-al-seleccionar-una-valvula-de-control-para-servicio-de-vapor-industrial\/\" target=\"_blank\" rel=\"noopener noreferrer\"><b>v\u00e1lvula de controle<\/b><\/a><span style=\"font-weight: 400;\"> a press\u00e3o nos permutadores de vapor de placas depender\u00e1 do servi\u00e7o realmente necess\u00e1rio e da \u00e1rea de transfer\u00eancia de calor dispon\u00edvel no permutador.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-8696\" src=\"\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/07\/Intercambiadores-de-vapor-de-placas-2.jpg\" alt=\"\" width=\"1200\" height=\"600\" srcset=\"https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/07\/Intercambiadores-de-vapor-de-placas-2-150x75.jpg 150w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/07\/Intercambiadores-de-vapor-de-placas-2-300x150.jpg 300w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/07\/Intercambiadores-de-vapor-de-placas-2-600x300.jpg 600w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/07\/Intercambiadores-de-vapor-de-placas-2-768x384.jpg 768w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/07\/Intercambiadores-de-vapor-de-placas-2-800x400.jpg 800w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/07\/Intercambiadores-de-vapor-de-placas-2-1024x512.jpg 1024w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/07\/Intercambiadores-de-vapor-de-placas-2.jpg 1200w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Note-se que neste exemplo, a plena carga, n\u00e3o haver\u00e1 condi\u00e7\u00e3o de corte, j\u00e1 que a press\u00e3o na entrada do al\u00e7ap\u00e3o ser\u00e1 de 0,5 bar r, dando uma press\u00e3o diferencial de 0,5 bar atrav\u00e9s do al\u00e7ap\u00e3o. Existe uma condi\u00e7\u00e3o de corte quando a press\u00e3o de entrada da armadilha \u00e9 de 0 bar r ou menos. A esta press\u00e3o, a temperatura do vapor deve ser de 100oC.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Isto pode acontecer quando uma, ou uma combina\u00e7\u00e3o das seguintes coisas acontece:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">As temperaturas de entrada e sa\u00edda do permutador secund\u00e1rio (DT no lado secund\u00e1rio) permanecem constantes, mas o caudal \u00e9 reduzido.<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">O caudal permanece constante mas o DT do secund\u00e1rio \u00e9 reduzido - A temperatura de entrada sobe ou a temperatura de sa\u00edda desce ou ambas.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">O ponto em que qualquer uma destas coisas acontece pode ser previsto atrav\u00e9s de c\u00e1lculos.\u00a0<\/span><span style=\"font-weight: 400;\">Tanto a diferen\u00e7a de temperatura m\u00e9dia logar\u00edtmica (lmtd) como a diferen\u00e7a de temperatura m\u00e9dia aritm\u00e9tica (amtd) podem ser usadas nos c\u00e1lculos. O uso de lmtd \u00e9 tecnicamente correto, enquanto o amtd \u00e9 mais simples de usar.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Os c\u00e1lculos neste manual utilizam amtd e fornecem solu\u00e7\u00f5es suficientemente precisas para o uso pr\u00e1tico do dia-a-dia. Os c\u00e1lculos tamb\u00e9m assumem um valor constante de k em todas as condi\u00e7\u00f5es; na pr\u00e1tica o valor de k varia \u00e0 medida que as velocidades e temperaturas do meio s\u00e3o alteradas.<\/span><\/p>\n<blockquote><p><span style=\"font-weight: 400;\">Um c\u00e1lculo para prever a redu\u00e7\u00e3o do fluxo que produzir\u00e1 uma condi\u00e7\u00e3o de interrup\u00e7\u00e3o \u00e9 mostrado na f\u00f3rmula localizada na primeira imagem deste artigo.<\/span><\/p><\/blockquote>\n<p><span style=\"font-weight: 400;\">Uma vez calculada, esta fra\u00e7\u00e3o pode ser aplicada \u00e0 taxa de fluxo de carga total para prever quando a interrup\u00e7\u00e3o ocorrer\u00e1. No nosso exemplo, a interrup\u00e7\u00e3o ocorrer\u00e1 quando a vaz\u00e3o cair abaixo de 3,1 kg\/s (4 kg\/s x 0,77). Este c\u00e1lculo expressa, com efeito, a amtd no ponto de interrup\u00e7\u00e3o como uma fra\u00e7\u00e3o da amtd a plena carga.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">No c\u00e1lculo da fra\u00e7\u00e3o a ser aplicada, a fim de prever quanto o DT secund\u00e1rio deve ser reduzido (o aumento de temperatura no lado secund\u00e1rio) para que a falta de energia ocorra, \u00e9 utilizada a f\u00f3rmula \"D\", que expressa a diferen\u00e7a de temperaturas entre o vapor e a sa\u00edda secund\u00e1ria, em plena carga, e com a falta de energia expressa como fra\u00e7\u00e3o.\u00a0<\/span><\/p>\n<blockquote><p><span style=\"font-weight: 400;\">Uma vez calculada, esta fra\u00e7\u00e3o pode ser aplicada ao DT do secund\u00e1rio em plena carga para prever quando ocorrer\u00e1 a falta de energia.\u00a0<\/span><\/p><\/blockquote>\n<p><span style=\"font-weight: 400;\">Neste caso, ser\u00e1 quando o DT do secund\u00e1rio cair para 27oC (60oC x 0,45) ou menos. Portanto, se a temperatura de sa\u00edda for mantida a 90oC, haver\u00e1 interrup\u00e7\u00e3o se a temperatura de entrada subir para 63oC (90oC-27oC).<\/span><\/p>\n<p><script src=\"\/\/fast.wistia.com\/embed\/medias\/0fx27xskly.jsonp\" async><\/script><script src=\"\/\/fast.wistia.com\/assets\/external\/E-v1.js\" async><\/script><\/p>\n<div class=\"wistia_responsive_padding\" style=\"padding: 56.25% 0 0 0; position: relative;\">\n<div class=\"wistia_responsive_wrapper\" style=\"height: 100%; left: 0; position: absolute; top: 0; width: 100%;\">\n<div class=\"wistia_embed wistia_async_0fx27xskly videoFoam=true\" style=\"height: 100%; position: relative; width: 100%;\">\n<div class=\"wistia_swatch\" style=\"height: 100%; left: 0; opacity: 0; overflow: hidden; position: absolute; top: 0; transition: opacity 200ms; width: 100%;\"><img decoding=\"async\" style=\"filter: blur(5px); height: 100%; object-fit: contain; width: 100%;\" src=\"\/\/fast.wistia.com\/embed\/medias\/0fx27xskly\/swatch\" alt=\"\" \/><\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Para saber como calcular a <\/span><a href=\"https:\/\/vaporparalaindustria.com\/pt\/control-de-temperatura-en-intercambiadores-de-calor-de-placas-para-vapor-parte-1\/\" target=\"_blank\" rel=\"noopener noreferrer\"><b>controlo de temperatura em permutadores de calor de placas de vapor<\/b><\/a><span style=\"font-weight: 400;\">subscreva o\u00a0<\/span><a href=\"https:\/\/vaporparalaindustria.com\/pt\/newsletter\/?utm_source=newsletter&amp;utm_medium=cta_vapor&amp;utm_campaign=vapor_cta_newsletter\" target=\"_blank\" rel=\"noopener noreferrer\"><b>Boletim Informativo Steam for Industry<\/b><\/a><span style=\"font-weight: 400;\">As novas tend\u00eancias do vapor industrial, um recurso que o ajudar\u00e1 a receber mais conte\u00fado sobre as novas tend\u00eancias do vapor industrial, com artigos como o <\/span><a href=\"https:\/\/vaporparalaindustria.com\/pt\/normativas-para-el-uso-del-vapor-en-el-sector-alimentacion-y-bebidas\/\" target=\"_blank\" rel=\"noopener noreferrer\"><b>regulamentos para o uso de vapor no setor de alimentos e bebidas<\/b><\/a><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><a href=\"\/\/vaporparalaindustria.com\/pt\/auditoria-gratuita-de-calidad-del-vapor-para-procesos-alimentarios\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-7581 size-full\" src=\"\/\/vaporparalaindustria.com\/wp-content\/uploads\/2018\/07\/evaluacion-gratuita-procesos-alimentarios.003.jpeg\" alt=\"AVALIA\u00c7\u00c3O DO VAPOR SISTEMA E CONDENSADO.001\" width=\"802\" height=\"181\" srcset=\"https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2018\/07\/evaluacion-gratuita-procesos-alimentarios.003-150x34.jpeg 150w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2018\/07\/evaluacion-gratuita-procesos-alimentarios.003-300x68.jpeg 300w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2018\/07\/evaluacion-gratuita-procesos-alimentarios.003-600x135.jpeg 600w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2018\/07\/evaluacion-gratuita-procesos-alimentarios.003-768x173.jpeg 768w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2018\/07\/evaluacion-gratuita-procesos-alimentarios.003-800x181.jpeg 800w, https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2018\/07\/evaluacion-gratuita-procesos-alimentarios.003.jpeg 802w\" sizes=\"auto, (max-width: 802px) 100vw, 802px\" \/><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Se a contrapress\u00e3o imposta a uma armadilha for maior do que a press\u00e3o dispon\u00edvel na sua entrada, diz-se que os permutadores de vapor de placas est\u00e3o em \"condi\u00e7\u00e3o de corte\". O condensado n\u00e3o pode passar atrav\u00e9s da armadilha e flui para tr\u00e1s, resultando na perda do controle efetivo sobre o trocador. O ponto em que ...<\/p>","protected":false},"author":1,"featured_media":8697,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[78,86],"tags":[],"class_list":["type-post","category-intercambiadores-de-calor-con-vapor","category-transferencia-de-calor","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Condici\u00f3n de interrupci\u00f3n en intercambiadores de vapor de placas<\/title>\n<meta name=\"description\" content=\"La condici\u00f3n de interrupci\u00f3n en intercambiadores de vapor de placas ocurre cuando la contrapresi\u00f3n impuesta a un purgador es mayor que la presi\u00f3n disponible.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vaporparalaindustria.com\/pt\/condicion-de-interrupcion-en-intercambiadores-de-vapor-de-placas-parte-2\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Condici\u00f3n de interrupci\u00f3n en intercambiadores de vapor de placas\" \/>\n<meta property=\"og:description\" content=\"La condici\u00f3n de interrupci\u00f3n en intercambiadores de vapor de placas ocurre cuando la contrapresi\u00f3n impuesta a un purgador es mayor que la presi\u00f3n disponible.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vaporparalaindustria.com\/pt\/condicion-de-interrupcion-en-intercambiadores-de-vapor-de-placas-parte-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Vapor para la Industria\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-24T08:00:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-11T13:39:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/07\/Intercambiadores-de-vapor-de-placas-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Soporte\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Soporte\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vaporparalaindustria.com\\\/condicion-de-interrupcion-en-intercambiadores-de-vapor-de-placas-parte-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vaporparalaindustria.com\\\/condicion-de-interrupcion-en-intercambiadores-de-vapor-de-placas-parte-2\\\/\"},\"author\":{\"name\":\"Soporte\",\"@id\":\"https:\\\/\\\/vaporparalaindustria.com\\\/#\\\/schema\\\/person\\\/d64ca106960ba7ec5a51834fbecba681\"},\"headline\":\"Condici\u00f3n de interrupci\u00f3n en intercambiadores de vapor de placas (Parte 2)\",\"datePublished\":\"2019-07-24T08:00:45+00:00\",\"dateModified\":\"2020-06-11T13:39:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vaporparalaindustria.com\\\/condicion-de-interrupcion-en-intercambiadores-de-vapor-de-placas-parte-2\\\/\"},\"wordCount\":948,\"publisher\":{\"@id\":\"https:\\\/\\\/vaporparalaindustria.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vaporparalaindustria.com\\\/condicion-de-interrupcion-en-intercambiadores-de-vapor-de-placas-parte-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vaporparalaindustria.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/Intercambiadores-de-vapor-de-placas-1.jpg\",\"articleSection\":[\"Intercambiadores de Calor con Vapor\",\"Transferencia de Calor\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vaporparalaindustria.com\\\/condicion-de-interrupcion-en-intercambiadores-de-vapor-de-placas-parte-2\\\/\",\"url\":\"https:\\\/\\\/vaporparalaindustria.com\\\/condicion-de-interrupcion-en-intercambiadores-de-vapor-de-placas-parte-2\\\/\",\"name\":\"Condici\u00f3n de interrupci\u00f3n en intercambiadores de vapor de placas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vaporparalaindustria.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vaporparalaindustria.com\\\/condicion-de-interrupcion-en-intercambiadores-de-vapor-de-placas-parte-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vaporparalaindustria.com\\\/condicion-de-interrupcion-en-intercambiadores-de-vapor-de-placas-parte-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vaporparalaindustria.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/Intercambiadores-de-vapor-de-placas-1.jpg\",\"datePublished\":\"2019-07-24T08:00:45+00:00\",\"dateModified\":\"2020-06-11T13:39:59+00:00\",\"description\":\"La condici\u00f3n de interrupci\u00f3n en intercambiadores de vapor de placas ocurre cuando la contrapresi\u00f3n impuesta a un purgador es mayor que la presi\u00f3n disponible.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vaporparalaindustria.com\\\/condicion-de-interrupcion-en-intercambiadores-de-vapor-de-placas-parte-2\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vaporparalaindustria.com\\\/condicion-de-interrupcion-en-intercambiadores-de-vapor-de-placas-parte-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/vaporparalaindustria.com\\\/condicion-de-interrupcion-en-intercambiadores-de-vapor-de-placas-parte-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vaporparalaindustria.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/Intercambiadores-de-vapor-de-placas-1.jpg\",\"contentUrl\":\"https:\\\/\\\/vaporparalaindustria.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/Intercambiadores-de-vapor-de-placas-1.jpg\",\"width\":1200,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vaporparalaindustria.com\\\/condicion-de-interrupcion-en-intercambiadores-de-vapor-de-placas-parte-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vaporparalaindustria.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Condici\u00f3n de interrupci\u00f3n en intercambiadores de vapor de placas (Parte 2)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vaporparalaindustria.com\\\/#website\",\"url\":\"https:\\\/\\\/vaporparalaindustria.com\\\/\",\"name\":\"Vapor para la Industria\",\"description\":\"Gesti\u00f3n Eficiente de los Sistemas de Vapor\",\"publisher\":{\"@id\":\"https:\\\/\\\/vaporparalaindustria.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vaporparalaindustria.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vaporparalaindustria.com\\\/#organization\",\"name\":\"Vapor para la Industria\",\"url\":\"https:\\\/\\\/vaporparalaindustria.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/vaporparalaindustria.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/vaporparalaindustria.com\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/LogoBlogBLANCO-FINAL_VAPOR-PARA-LA-INDUSTRIA-e1499957507814.png\",\"contentUrl\":\"https:\\\/\\\/vaporparalaindustria.com\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/LogoBlogBLANCO-FINAL_VAPOR-PARA-LA-INDUSTRIA-e1499957507814.png\",\"width\":300,\"height\":117,\"caption\":\"Vapor para la Industria\"},\"image\":{\"@id\":\"https:\\\/\\\/vaporparalaindustria.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vaporparalaindustria.com\\\/#\\\/schema\\\/person\\\/d64ca106960ba7ec5a51834fbecba681\",\"name\":\"Soporte\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/daafa31e3c3038855edc007ca2e41a7f1af1259b6b79b93359d6de82934c5943?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/daafa31e3c3038855edc007ca2e41a7f1af1259b6b79b93359d6de82934c5943?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/daafa31e3c3038855edc007ca2e41a7f1af1259b6b79b93359d6de82934c5943?s=96&d=mm&r=g\",\"caption\":\"Soporte\"},\"url\":\"https:\\\/\\\/vaporparalaindustria.com\\\/pt\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Condi\u00e7\u00e3o de interrup\u00e7\u00e3o em permutadores de calor de placas","description":"A situa\u00e7\u00e3o de interrup\u00e7\u00e3o nos permutadores de calor de placas ocorre quando a contrapress\u00e3o exercida sobre um purgador \u00e9 superior \u00e0 press\u00e3o dispon\u00edvel.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vaporparalaindustria.com\/pt\/condicion-de-interrupcion-en-intercambiadores-de-vapor-de-placas-parte-2\/","og_locale":"pt_PT","og_type":"article","og_title":"Condici\u00f3n de interrupci\u00f3n en intercambiadores de vapor de placas","og_description":"La condici\u00f3n de interrupci\u00f3n en intercambiadores de vapor de placas ocurre cuando la contrapresi\u00f3n impuesta a un purgador es mayor que la presi\u00f3n disponible.","og_url":"https:\/\/vaporparalaindustria.com\/pt\/condicion-de-interrupcion-en-intercambiadores-de-vapor-de-placas-parte-2\/","og_site_name":"Vapor para la Industria","article_published_time":"2019-07-24T08:00:45+00:00","article_modified_time":"2020-06-11T13:39:59+00:00","og_image":[{"width":1200,"height":600,"url":"https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/07\/Intercambiadores-de-vapor-de-placas-1.jpg","type":"image\/jpeg"}],"author":"Soporte","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Soporte","Tempo estimado de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vaporparalaindustria.com\/condicion-de-interrupcion-en-intercambiadores-de-vapor-de-placas-parte-2\/#article","isPartOf":{"@id":"https:\/\/vaporparalaindustria.com\/condicion-de-interrupcion-en-intercambiadores-de-vapor-de-placas-parte-2\/"},"author":{"name":"Soporte","@id":"https:\/\/vaporparalaindustria.com\/#\/schema\/person\/d64ca106960ba7ec5a51834fbecba681"},"headline":"Condici\u00f3n de interrupci\u00f3n en intercambiadores de vapor de placas (Parte 2)","datePublished":"2019-07-24T08:00:45+00:00","dateModified":"2020-06-11T13:39:59+00:00","mainEntityOfPage":{"@id":"https:\/\/vaporparalaindustria.com\/condicion-de-interrupcion-en-intercambiadores-de-vapor-de-placas-parte-2\/"},"wordCount":948,"publisher":{"@id":"https:\/\/vaporparalaindustria.com\/#organization"},"image":{"@id":"https:\/\/vaporparalaindustria.com\/condicion-de-interrupcion-en-intercambiadores-de-vapor-de-placas-parte-2\/#primaryimage"},"thumbnailUrl":"https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/07\/Intercambiadores-de-vapor-de-placas-1.jpg","articleSection":["Intercambiadores de Calor con Vapor","Transferencia de Calor"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/vaporparalaindustria.com\/condicion-de-interrupcion-en-intercambiadores-de-vapor-de-placas-parte-2\/","url":"https:\/\/vaporparalaindustria.com\/condicion-de-interrupcion-en-intercambiadores-de-vapor-de-placas-parte-2\/","name":"Condi\u00e7\u00e3o de interrup\u00e7\u00e3o em permutadores de calor de placas","isPartOf":{"@id":"https:\/\/vaporparalaindustria.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vaporparalaindustria.com\/condicion-de-interrupcion-en-intercambiadores-de-vapor-de-placas-parte-2\/#primaryimage"},"image":{"@id":"https:\/\/vaporparalaindustria.com\/condicion-de-interrupcion-en-intercambiadores-de-vapor-de-placas-parte-2\/#primaryimage"},"thumbnailUrl":"https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/07\/Intercambiadores-de-vapor-de-placas-1.jpg","datePublished":"2019-07-24T08:00:45+00:00","dateModified":"2020-06-11T13:39:59+00:00","description":"A situa\u00e7\u00e3o de interrup\u00e7\u00e3o nos permutadores de calor de placas ocorre quando a contrapress\u00e3o exercida sobre um purgador \u00e9 superior \u00e0 press\u00e3o dispon\u00edvel.","breadcrumb":{"@id":"https:\/\/vaporparalaindustria.com\/condicion-de-interrupcion-en-intercambiadores-de-vapor-de-placas-parte-2\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vaporparalaindustria.com\/condicion-de-interrupcion-en-intercambiadores-de-vapor-de-placas-parte-2\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/vaporparalaindustria.com\/condicion-de-interrupcion-en-intercambiadores-de-vapor-de-placas-parte-2\/#primaryimage","url":"https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/07\/Intercambiadores-de-vapor-de-placas-1.jpg","contentUrl":"https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/07\/Intercambiadores-de-vapor-de-placas-1.jpg","width":1200,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/vaporparalaindustria.com\/condicion-de-interrupcion-en-intercambiadores-de-vapor-de-placas-parte-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vaporparalaindustria.com\/"},{"@type":"ListItem","position":2,"name":"Condici\u00f3n de interrupci\u00f3n en intercambiadores de vapor de placas (Parte 2)"}]},{"@type":"WebSite","@id":"https:\/\/vaporparalaindustria.com\/#website","url":"https:\/\/vaporparalaindustria.com\/","name":"Vapor para a Ind\u00fastria","description":"Gest\u00e3o Eficiente de Sistemas a Vapor","publisher":{"@id":"https:\/\/vaporparalaindustria.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vaporparalaindustria.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/vaporparalaindustria.com\/#organization","name":"Vapor para a Ind\u00fastria","url":"https:\/\/vaporparalaindustria.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/vaporparalaindustria.com\/#\/schema\/logo\/image\/","url":"https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2017\/10\/LogoBlogBLANCO-FINAL_VAPOR-PARA-LA-INDUSTRIA-e1499957507814.png","contentUrl":"https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2017\/10\/LogoBlogBLANCO-FINAL_VAPOR-PARA-LA-INDUSTRIA-e1499957507814.png","width":300,"height":117,"caption":"Vapor para la Industria"},"image":{"@id":"https:\/\/vaporparalaindustria.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/vaporparalaindustria.com\/#\/schema\/person\/d64ca106960ba7ec5a51834fbecba681","name":"Suporte","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/daafa31e3c3038855edc007ca2e41a7f1af1259b6b79b93359d6de82934c5943?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/daafa31e3c3038855edc007ca2e41a7f1af1259b6b79b93359d6de82934c5943?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/daafa31e3c3038855edc007ca2e41a7f1af1259b6b79b93359d6de82934c5943?s=96&d=mm&r=g","caption":"Soporte"},"url":"https:\/\/vaporparalaindustria.com\/pt\/author\/admin\/"}]}},"acf":[],"fimg_url":"https:\/\/vaporparalaindustria.com\/wp-content\/uploads\/2019\/07\/Intercambiadores-de-vapor-de-placas-1.jpg","_links":{"self":[{"href":"https:\/\/vaporparalaindustria.com\/pt\/wp-json\/wp\/v2\/posts\/8694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vaporparalaindustria.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vaporparalaindustria.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vaporparalaindustria.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vaporparalaindustria.com\/pt\/wp-json\/wp\/v2\/comments?post=8694"}],"version-history":[{"count":0,"href":"https:\/\/vaporparalaindustria.com\/pt\/wp-json\/wp\/v2\/posts\/8694\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vaporparalaindustria.com\/pt\/wp-json\/wp\/v2\/media\/8697"}],"wp:attachment":[{"href":"https:\/\/vaporparalaindustria.com\/pt\/wp-json\/wp\/v2\/media?parent=8694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vaporparalaindustria.com\/pt\/wp-json\/wp\/v2\/categories?post=8694"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vaporparalaindustria.com\/pt\/wp-json\/wp\/v2\/tags?post=8694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}